{"id":32218,"date":"2021-07-09T17:14:44","date_gmt":"2021-07-09T15:14:44","guid":{"rendered":"https:\/\/www.wojo.com\/blog\/?p=32218"},"modified":"2023-01-21T23:22:32","modified_gmt":"2023-01-21T22:22:32","slug":"8-tipps-fur-erfolgreiches-remote-brainstorming","status":"publish","type":"post","link":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/","title":{"rendered":"8 Tipps f\u00fcr erfolgreiche Remote-Brainstormings"},"content":{"rendered":"<p><!-- wp:paragraph --><\/p>\n<p><strong>Der Name eines neuen Produkts, einer Dienstleistung oder eines Projekts, Probleml\u00f6sungen, ausgefallene Ideen, um neue Kunden zu verf\u00fchren, \u00dcberlegungen zu einer Verpackung... Die M\u00f6glichkeiten, ein Brainstorming zu organisieren, sind zahlreich... und die Gr\u00fcnde, es zu verpassen, noch mehr. Mit der Verallgemeinerung der <\/strong><strong>Fernarbeit erfordert die Organisation eines effizienten kreativen Meetings Strenge: Wir teilen mit Ihnen die besten Praktiken, die anzuwenden sind.<\/strong><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>1 - Setzen Sie die richtigen Werkzeuge ein<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Um ein Remote-Brainstorming durchzuf\u00fchren, ben\u00f6tigen Sie ein <strong>Videokonferenz-Tool<\/strong>. Einige sind kostenlos, wie <a href=\"https:\/\/meet.jit.si\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jitsi <\/a>oder <a href=\"https:\/\/www.skype.com\/fr\/\">Skype<\/a>, andere sind kostenpflichtig oder in umfassendere Kollaborationsl\u00f6sungen (<a href=\"https:\/\/www.microsoft.com\/fr-fr\/microsoft-365\/microsoft-teams\/group-chat-software\" target=\"_blank\" rel=\"noreferrer noopener\">Teams<\/a>, <a href=\"https:\/\/www.talkspirit.com\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Talkspirit<\/a>, etc.) integriert.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Au\u00dferdem ben\u00f6tigen Sie <strong>ein kollaboratives Whiteboard <\/strong>(<a href=\"https:\/\/draw.chat\/\" target=\"_blank\" rel=\"noreferrer noopener\">Drawchat<\/a>, <a href=\"https:\/\/klaxoon.com\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">Klaxoon<\/a>, <a href=\"https:\/\/www.mural.co\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mural<\/a>, etc.). Wenn die Teams mit diesen Tools nicht vertraut sind, <strong>schicken Sie in Ihrer Einladung eine kurze Bedienungsanleitung mit und erlauben Sie zehn Minuten praktische \u00dcbungen, um <\/strong>das Brainstorming zu beginnen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Im Klassenzimmer werden die eingehenden Ideen auf Post-it-Zetteln notiert, die an die Wand des Besprechungsraums geklebt werden. Im digitalen Modus kann das kollaborative Whiteboard verwendet werden, um sie aufzulisten, Moodboards anzuzeigen, Diagramme zu erstellen, Assoziationen zu erzeugen... Kurz gesagt, um die Kreativit\u00e4t aller zu n\u00e4hren und alle Ideen zu zentralisieren, auch die weit hergeholten! Das ist der Sinn des Brainstormings: Eine Verbindung zwischen zwei unerwarteten Ideen kann zu einer gro\u00dfen Idee f\u00fchren, die extrem effektiv ist.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>2 - Den Rahmen f\u00fcr das Brainstorming setzen<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Wonach suchen Sie? <strong>Schreiben Sie vor dem <\/strong>Treffen <strong>ein pr\u00e4zises Briefing<\/strong>, in dem Sie das Thema (Produkt, Problem, Dienstleistung, Projekt usw.), \u00fcber das Sie Ihre Kollegen zum Nachdenken einladen, sowie die Ziele beschreiben. Dies ist eine wichtige \u00dcbung, die es Ihnen erm\u00f6glicht, Ihre Gedanken zu formulieren, um sicherzustellen, dass sie Ihren Bed\u00fcrfnissen entsprechen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>3 - Auswahl der richtigen Besetzung<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Quantit\u00e4t ist nicht immer gleich Qualit\u00e4t, besonders wenn es darum geht, eine F\u00fclle von Ideen zu generieren. Die richtige Zahl? <strong>Mindestens sechs Personen, um eine gute Dynamik zu gew\u00e4hrleisten, aber nicht mehr als zehn<\/strong>, da es bei einer Videokonferenz schwierig wird, die Anzahl der Personen zu verwalten. Der Fehler, den man nicht machen sollte: die gesamte Kommunikationsabteilung einladen und die anderen Teams vergessen. Ein gutes Brainstorming ist eines, das neue Visionen hervorbringt. Es geht nichts \u00fcber eine gemischte Besetzung mit Mitwirkenden aus verschiedenen Bereichen, um aus den gewohnten Bahnen herauszukommen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>4 - Legen Sie die Regeln f\u00fcr das Brainstorming fest<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><strong>Beauftragen Sie einen Moderator mit der Durchsetzung des Zeitplans der \u00dcbungen und der Verteilung des Wortes, <\/strong>und legen Sie zu Beginn der Videokonferenz Regeln fest.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Nur das Mikrofon des Moderators ist offen, und die Teilnehmer heben die Hand, um der Reihe nach zu sprechen oder auf einen Vorschlag zu reagieren, der gerade gemacht wurde. <strong>Kritik ist nicht erlaubt<\/strong>, die Teilnehmer sind nicht dazu da, die Ideen der anderen zu beurteilen. Es wird eine Strafe geben (virtuelle Kaffeerunde, Zeichnung eines haarigen Monsters, etc.) f\u00fcr diejenigen, die sich nicht daran halten. Handys sind ebenfalls verboten: Bitten Sie alle, ihr Telefon zu Beginn des Brainstorming-Treffens auf Flugmodus zu stellen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Haben Sie auch eine Sekret\u00e4rin, die alle Ideen, die vorgebracht werden, \u00fcber ein gemeinsames, interaktives Whiteboard aufschreibt, so dass jeder jederzeit sehen kann, was vorgeschlagen wurde. Dies kann in den n\u00e4chsten Schritten zu unerwarteten Assoziationen f\u00fchren.&nbsp;<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>5 - Organisieren Sie Eisbrecher<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Eine Brainstorming-Sitzung per Videokonferenz statt pers\u00f6nlich zu veranstalten, ist ein Eisbrecher an sich. <strong>Die Teilnehmer sind au\u00dferhalb des B\u00fcros und ihres gewohnten Umfelds, was die Kreativit\u00e4t f\u00f6rdert<\/strong>. \u00dcbungen zum Umgang mit dem kollaborativen Whiteboard k\u00f6nnen auch Eisbrecher sein, dank am\u00fcsanter Visualisierungen, die die Teilnehmer manipulieren m\u00fcssen, einer Karte von Frankreich, auf der sie sich positionieren k\u00f6nnen, usw.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Andere Ideen: Fordern Sie jeden auf, ein Accessoire seiner Wahl zu w\u00e4hlen und es dem Rest der Gruppe zu erkl\u00e4ren. Sie k\u00f6nnen auch jede Person bitten, zu erz\u00e4hlen, was sie zu Beginn des Tages gemacht hat, aber ohne \u00fcber die Arbeit zu sprechen, was sie gestern Abend gegessen hat und wer es zubereitet hat, kurz gesagt, alles, was ihnen hilft, anders als gew\u00f6hnlich zu denken.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>6 - Planen Sie mehrere verschiedene \u00dcbungen<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Es gibt viele Brainstorming-Techniken, und ihr Ziel ist es, den ber\u00fchmten \"Ideensturm\" hervorzubringen, den Sie suchen! <strong>Hier sind einige von ihnen, angepasst an ein Videokonferenz-Meeting, <\/strong>um Ihnen beim Aufbau Ihres Programms zu helfen. Jede \u00dcbung sollte zwischen 10 und 15 Minuten dauern.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Die leere Seite<\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Bitten Sie zum Aufw\u00e4rmen alle, in einem gemeinsamen Dokument alles aufzuschreiben, was ihnen wichtig erscheint und was sie gerne \u00fcber das Projekt \/ die Dienstleistung \/ das Produkt, \u00fcber das Sie sich treffen, wissen m\u00f6chten. Es geht in alle Richtungen? Das ist gut so!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Die stille Tour<\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Bitten Sie alle, eine Frage zu dem Produkt\/Dienstleistung\/Projekt, \u00fcber das Sie nachdenken, auf die virtuelle Tafel zu schreiben. Geben Sie der Gruppe dann 10 Minuten Zeit, um ihre Antwort auf die Frage mit Hilfe von Zetteln, die neben die Frage geklebt werden, zu erg\u00e4nzen. Dies ist eine empfohlene \u00dcbung, wenn Sie sch\u00fcchterne Personen in der Gruppe haben!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Das Rollenspiel<\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Jeder Teilnehmer w\u00e4hlt eine Pers\u00f6nlichkeit und versetzt sich f\u00fcr die Dauer der \u00dcbung in deren Lage. Madonna, Emmanuel Macron, Jeff Bezos, Mickey Mouse... werden Jean-Michel, Nadia, Houcine und Oph\u00e9lie auf dem Bildschirm ersetzen und ihre Sichtweise auf das Produkt \/ die Dienstleistung \/ das Projekt in den eingereichten Ideen vorschlagen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading {\"level\":3} --><\/p>\n<h3>Zeichnen Sie mir eine Idee<\/h3>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Jeder Mitarbeiter zeichnet auf einem Teil der virtuellen Tafel ein Bild, das mit dem produzierten Projekt \/ der Dienstleistung zusammenh\u00e4ngt, oder einen Gedankengang, der seiner Meinung nach erforscht werden sollte. Jede Zeichnung geht dann im Uhrzeigersinn um das Team herum, und jede Person f\u00fcgt ein weiteres Bild hinzu. Die Diskussion \u00fcber die endg\u00fcltigen Bilder wird unerwartete Assoziationen und Ideen hervorbringen.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>7 - Demokratische Prinzipien anwenden<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Das Risiko in einer Brainstorming-Sitzung besteht darin, dass diejenigen, die am lautesten sprechen, die anderen von der Richtigkeit ihrer Ideen \u00fcberzeugen. Um dies zu vermeiden, <strong>beenden Sie Ihr Meeting, indem Sie allen f\u00fcnf Minuten Zeit geben, f\u00fcr die drei Ideen abzustimmen, die ihnen am besten gefallen<\/strong>, indem sie ein kleines Kreuz oder ein virtuelles Post-it anbringen. Die beiden Ideen, die die meisten Stimmen erhalten, werden dann entwickelt!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><em>Lesen Sie auch&nbsp;: <a href=\"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/2021\/07\/01\/wie-zu-werben-und-an-einem-bord-zu-bleiben\" target=\"_blank\" rel=\"noreferrer noopener\">Wie rekrutiert und onboardet man aus der Ferne?<\/a><\/em><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h2>8 - W\u00e4hlen Sie einen Ort au\u00dferhalb der Box, um sich zu treffen<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Der ideale Weg f\u00fcr ein effizientes Brainstorming ist immer noch, sich von Angesicht zu Angesicht am selben Ort zu treffen. Dies sollte in den kommenden Monaten allm\u00e4hlich wieder m\u00f6glich werden, zumindest hoffen wir das. <strong>Um die Kreativit\u00e4t der Teilnehmer zu stimulieren, gibt es nichts Besseres, als ihnen ein Meeting au\u00dferhalb des B\u00fcros oder an einem ungew\u00f6hnlichen Ort zu geben<\/strong>: in einem Park, einem geselligen Ort, einem Coworking Space, der atypische Meeting-R\u00e4ume anbietet... es liegt an Ihnen, je nach Jahreszeit und dem Thema Ihres Brainstormings zu w\u00e4hlen!<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:buttons {\"layout\":{\"type\":\"flex\",\"justifyContent\":\"center\",\"orientation\":\"horizontal\"}} --><\/p>\n<div class=\"wp-block-buttons\"><!-- wp:button {\"backgroundColor\":\"vivid-cyan-blue\"} --><\/p>\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-vivid-cyan-blue-background-color has-background\" href=\"https:\/\/www.wojo.com\/de-DE\" target=\"_blank\" rel=\"noreferrer noopener\">Entdecken Sie Wojo Tagungsr\u00e4ume<\/a><\/div>\n<p><!-- \/wp:button --><\/div>\n<p><!-- \/wp:buttons --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p><!-- \/wp:paragraph --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Name eines neuen Produkts, einer Dienstleistung oder eines Projekts, Probleml\u00f6sungen, ausgefallene Ideen, um neue Kunden zu verf\u00fchren, \u00dcberlegungen zu einer Verpackung... Die M\u00f6glichkeiten, ein Brainstorming zu organisieren, sind zahlreich... und die Gr\u00fcnde, es zu verpassen, noch mehr. Mit der Verallgemeinerung der Fernarbeit erfordert die Organisation eines effizienten kreativen Meetings Strenge: Wir teilen mit Ihnen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30720,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"podcast_url_v2":"","footnotes":""},"categories":[524],"tags":[759,763,747,707,735,625],"class_list":["post-32218","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-der-werkzeugkasten","tag-innovation-de","tag-inspiration-de","tag-management-de","tag-networking-de","tag-qwl-de","tag-telearbeit-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>8 Tipps f\u00fcr erfolgreiches Remote-Brainstorming<\/title>\n<meta name=\"description\" content=\"Effektives Brainstorming l\u00e4sst sich nicht improvisieren, und schon gar nicht, wenn man in Telearbeit oder aus der Ferne arbeitet. Befolgen Sie diese goldenen Regeln f\u00fcr ein erfolgreiches Brainstorming.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"8 Tipps f\u00fcr erfolgreiches Remote-Brainstorming\" \/>\n<meta property=\"og:description\" content=\"Effektives Brainstorming l\u00e4sst sich nicht improvisieren, und schon gar nicht, wenn man in Telearbeit oder aus der Ferne arbeitet. Befolgen Sie diese goldenen Regeln f\u00fcr ein erfolgreiches Brainstorming.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Wojo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Wojo.coworking\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-09T15:14:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-21T22:22:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wojo.com\/blog\/wp-content\/uploads\/2020\/12\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wojo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Wojo_co\" \/>\n<meta name=\"twitter:site\" content=\"@Wojo_co\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wojo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/\"},\"author\":{\"name\":\"Wojo\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#\\\/schema\\\/person\\\/52175cfaea09e0d3479bdd89e2993639\"},\"headline\":\"8 Tipps f\u00fcr erfolgreiche Remote-Brainstormings\",\"datePublished\":\"2021-07-09T15:14:44+00:00\",\"dateModified\":\"2023-01-21T22:22:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/\"},\"wordCount\":1165,\"publisher\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg\",\"keywords\":[\"Innovation - DE\",\"Inspiration - DE\",\"Management - DE\",\"Networking -DE\",\"QWL - DE\",\"Telearbeit\"],\"articleSection\":[\"Der Werkzeugkasten\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/\",\"url\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/\",\"name\":\"8 Tipps f\u00fcr erfolgreiches Remote-Brainstorming\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg\",\"datePublished\":\"2021-07-09T15:14:44+00:00\",\"dateModified\":\"2023-01-21T22:22:32+00:00\",\"description\":\"Effektives Brainstorming l\u00e4sst sich nicht improvisieren, und schon gar nicht, wenn man in Telearbeit oder aus der Ferne arbeitet. Befolgen Sie diese goldenen Regeln f\u00fcr ein erfolgreiches Brainstorming.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Tips for successful remote brainstorming Wojo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/der-werkzeugkasten\\\/8-tipps-fur-erfolgreiches-remote-brainstorming\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Werkzeugkasten\",\"item\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/de\\\/category\\\/der-werkzeugkasten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"8 Tipps f\u00fcr erfolgreiche Remote-Brainstormings\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/\",\"name\":\"Blog Wojo\",\"description\":\"Work. Share. Live.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#organization\",\"name\":\"Wojo\",\"url\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Wojo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Wojo.coworking\\\/\",\"https:\\\/\\\/x.com\\\/Wojo_co\",\"https:\\\/\\\/instagram.com\\\/wojo_co\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/wojo-co\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCorVBPUgSsTQ3zUR9CYSp8Q\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.wojo.com\\\/blog\\\/#\\\/schema\\\/person\\\/52175cfaea09e0d3479bdd89e2993639\",\"name\":\"Wojo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"8 Tipps f\u00fcr erfolgreiches Remote-Brainstorming","description":"Effektives Brainstorming l\u00e4sst sich nicht improvisieren, und schon gar nicht, wenn man in Telearbeit oder aus der Ferne arbeitet. Befolgen Sie diese goldenen Regeln f\u00fcr ein erfolgreiches Brainstorming.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/","og_locale":"fr_FR","og_type":"article","og_title":"8 Tipps f\u00fcr erfolgreiches Remote-Brainstorming","og_description":"Effektives Brainstorming l\u00e4sst sich nicht improvisieren, und schon gar nicht, wenn man in Telearbeit oder aus der Ferne arbeitet. Befolgen Sie diese goldenen Regeln f\u00fcr ein erfolgreiches Brainstorming.","og_url":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/","og_site_name":"Blog Wojo","article_publisher":"https:\/\/www.facebook.com\/Wojo.coworking\/","article_published_time":"2021-07-09T15:14:44+00:00","article_modified_time":"2023-01-21T22:22:32+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/www.wojo.com\/blog\/wp-content\/uploads\/2020\/12\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Wojo","twitter_card":"summary_large_image","twitter_creator":"@Wojo_co","twitter_site":"@Wojo_co","twitter_misc":{"\u00c9crit par":"Wojo","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#article","isPartOf":{"@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/"},"author":{"name":"Wojo","@id":"https:\/\/www.wojo.com\/blog\/#\/schema\/person\/52175cfaea09e0d3479bdd89e2993639"},"headline":"8 Tipps f\u00fcr erfolgreiche Remote-Brainstormings","datePublished":"2021-07-09T15:14:44+00:00","dateModified":"2023-01-21T22:22:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/"},"wordCount":1165,"publisher":{"@id":"https:\/\/www.wojo.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wojo.com\/blog\/wp-content\/uploads\/2020\/12\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg","keywords":["Innovation - DE","Inspiration - DE","Management - DE","Networking -DE","QWL - DE","Telearbeit"],"articleSection":["Der Werkzeugkasten"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/","url":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/","name":"8 Tipps f\u00fcr erfolgreiches Remote-Brainstorming","isPartOf":{"@id":"https:\/\/www.wojo.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#primaryimage"},"image":{"@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wojo.com\/blog\/wp-content\/uploads\/2020\/12\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg","datePublished":"2021-07-09T15:14:44+00:00","dateModified":"2023-01-21T22:22:32+00:00","description":"Effektives Brainstorming l\u00e4sst sich nicht improvisieren, und schon gar nicht, wenn man in Telearbeit oder aus der Ferne arbeitet. Befolgen Sie diese goldenen Regeln f\u00fcr ein erfolgreiches Brainstorming.","breadcrumb":{"@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#primaryimage","url":"https:\/\/www.wojo.com\/blog\/wp-content\/uploads\/2020\/12\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg","contentUrl":"https:\/\/www.wojo.com\/blog\/wp-content\/uploads\/2020\/12\/sharon-pittaway-iMdsjoiftZo-unsplash-scaled.jpg","width":2560,"height":2560,"caption":"Tips for successful remote brainstorming Wojo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.wojo.com\/blog\/de\/der-werkzeugkasten\/8-tipps-fur-erfolgreiches-remote-brainstorming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wojo.com\/blog\/fr\/"},{"@type":"ListItem","position":2,"name":"Der Werkzeugkasten","item":"https:\/\/www.wojo.com\/blog\/de\/category\/der-werkzeugkasten\/"},{"@type":"ListItem","position":3,"name":"8 Tipps f\u00fcr erfolgreiche Remote-Brainstormings"}]},{"@type":"WebSite","@id":"https:\/\/www.wojo.com\/blog\/#website","url":"https:\/\/www.wojo.com\/blog\/","name":"Blog Wojo","description":"Work. Share. Live.","publisher":{"@id":"https:\/\/www.wojo.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wojo.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.wojo.com\/blog\/#organization","name":"Wojo","url":"https:\/\/www.wojo.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.wojo.com\/blog\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Wojo"},"image":{"@id":"https:\/\/www.wojo.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Wojo.coworking\/","https:\/\/x.com\/Wojo_co","https:\/\/instagram.com\/wojo_co\/","https:\/\/www.linkedin.com\/company\/wojo-co\/","https:\/\/www.youtube.com\/channel\/UCorVBPUgSsTQ3zUR9CYSp8Q"]},{"@type":"Person","@id":"https:\/\/www.wojo.com\/blog\/#\/schema\/person\/52175cfaea09e0d3479bdd89e2993639","name":"Wojo"}]}},"_links":{"self":[{"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/posts\/32218","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/comments?post=32218"}],"version-history":[{"count":0,"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/posts\/32218\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/media\/30720"}],"wp:attachment":[{"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/media?parent=32218"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/categories?post=32218"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wojo.com\/blog\/wp-json\/wp\/v2\/tags?post=32218"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}